{"id":2768,"date":"2010-05-20T17:36:18","date_gmt":"2010-05-20T15:36:18","guid":{"rendered":"https:\/\/www.herr-rau.de\/wordpress\/?p=2768"},"modified":"2023-05-24T16:20:52","modified_gmt":"2023-05-24T14:20:52","slug":"fundsachen-2","status":"publish","type":"post","link":"https:\/\/www.herr-rau.de\/wordpress\/2010\/05\/fundsachen-2.htm","title":{"rendered":"Fundsachen"},"content":{"rendered":"<div style='text-align:right;'><small>(<a href='https:\/\/www.herr-rau.de\/wordpress\/2010\/05\/fundsachen-2.htm#comments'>1 Kommentare.<\/a>)<\/small> <\/div>\n<p class=\"wp-block-paragraph\">1. <a href=\"http:\/\/www.apostrophe.at\/archives\/2321\">Lothar Bodingbauer verlinkt auf eine englische Seite<\/a>, bei der man auf einem Stadtplan die Schulen der Nachbarschaft abklappern kann und gleich angezeigt kriegt, wie gut oder schlecht diese Schulen laut offiziellen Erhebungen sind &#8211; Lehrerqualit\u00e4t, Sch\u00fclerzufriedenheit, Sch\u00fclerleistungen in verschiedenen Fachgebieten, grobe Einsch\u00e4tzung des Einkommens der Eltern:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Science results here are better than the local average.<\/li>\n\n\n\n<li>OFSTED says teaching standards here are lower than average.<\/li>\n\n\n\n<li>Fewer pupils get 5 GCSEs between A* and C than the local average.<\/li>\n\n\n\n<li>Official OFSTED grades for care &amp; guidance here are lower than average.<\/li>\n\n\n\n<li>The kids here need more experience of life outside school.<\/li>\n\n\n\n<li>The school isn&#8217;t showing many signs of improving.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">2. Die interessantesten Analysen zum Lehrersein finde ich immer wieder bei Maik Riecken. Lesenswert: seine Gedanken zu <a href=\"http:\/\/riecken.de\/index.php\/2009\/03\/macht-und-schule\/\">Macht und Schule<\/a>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Die ideelle Macht: Es gibt immer wieder Menschen, die sich durch besondere F\u00e4higkeiten an einer Schule hervortun. Das kann besonderes soziales Engagement, eine besondere p\u00e4dagogische F\u00e4higkeit, gewissenhafte Pflichterf\u00fcllung die \u00dcbernahme einer unangenehmen, aber notwendigen Aufgabe u.v.m. sein. Das System \u201cSchule\u201d w\u00e4re ohne solche Menschen um ein ganzes St\u00fcck weniger bunt, attraktiv und nicht zuletzt \u00e4rmer an Menschlichkeit.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fortgef\u00fchrt in <a href=\"http:\/\/riecken.de\/index.php\/2010\/01\/warum-schule-sich-kaum-verandert\/\">Warum Schule sich kaum ver\u00e4ndert<\/a>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Inhaber ideeller Macht erlebe ich an vielen Schulen oft als Motoren, als Vorreiter des p\u00e4dagogischen Fortschritts \u2013 somit sind sie Schmuckst\u00fccke der Au\u00dfendarstellung einer Schule. Da aber viele von ihnen ihr Engagement auf freiwillige Basis stellen, kann ihnen dieses Engagement nicht \u201cabverlangt\u201d werden. Man versucht dem zu begegnen, indem man Stellen schafft, die derartige Projekte in ihrer Beschreibung enthalten. Die ideellen Machtinhaber lehnen nach meiner Erfahrung diese Art der Dekoration oft genug ab, um sich die Option offenzuhalten, ebendieses Engagement auch wieder beliebig einstellen zu k\u00f6nnen, wenn der Rahmen nicht mehr passt.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses Verhalten kenne ich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und dann gibt es die sch\u00f6ne Reihe <a href=\"http:\/\/riecken.de\/index.php\/2010\/04\/resistance-is-futile-widerstand-ist-zwecklos-teil-1\/\">Widerstand ist zwecklos Teil 1<\/a> und <a href=\"http:\/\/riecken.de\/index.php\/2010\/05\/resistance-is-futile-widerstand-ist-zwecklos-teil-2\/\">Teil 2<\/a>. Im ersten Teil wird gezeigt, dass die innere K\u00fcndigung eine Reaktion darauf sein kann, dass der andere Vertragspartner &#8211; der Arbeitgeber, also bei mir das Kultusministerium &#8211; seine erwarteten Aufgaben nicht mehr wahrnimmt. Eine andere M\u00f6glichkeit des Widerstands gegen diese Arbeitsbedingungen besteht darin, dennoch zum munteren innovativ Engagierten zu werden, auf Vorgesetzte und Vorschriften zu pfeifen, und den Freiraum, den einem die F\u00fchrungslosigkeit bietet, auf Arten zu nutzen, die man selber f\u00fcr sinnvoll h\u00e4lt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maik h\u00e4lt es aber auch nicht f\u00fcr ideal, wenn sich jeder so auf seine eigene Art durchschl\u00e4gt, und fordert stattdessen Zusammenarbeit und Solidarit\u00e4t unter den Lehrern einer Schule &#8211; nicht im Netz, sondern vor allem vor Ort.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(1 Kommentare.) 1. Lothar Bodingbauer verlinkt auf eine englische Seite, bei der man auf einem Stadtplan die Schulen der Nachbarschaft abklappern kann und gleich angezeigt kriegt, wie gut oder schlecht diese Schulen laut offiziellen Erhebungen sind &#8211; Lehrerqualit\u00e4t, Sch\u00fclerzufriedenheit, Sch\u00fclerleistungen in verschiedenen Fachgebieten, grobe Einsch\u00e4tzung des Einkommens der Eltern: 2. Die interessantesten Analysen zum Lehrersein [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[37],"class_list":["post-2768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fundstuecke","tag-zusammenarbeit"],"jetpack_featured_media_url":"https:\/\/www.herr-rau.de\/wordpress\/archiv\/schooloscope.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/2768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2768"}],"version-history":[{"count":2,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/2768\/revisions"}],"predecessor-version":[{"id":58001,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/2768\/revisions\/58001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/media\/2769"}],"wp:attachment":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}