{"id":62454,"date":"2024-06-15T07:04:59","date_gmt":"2024-06-15T05:04:59","guid":{"rendered":"https:\/\/www.herr-rau.de\/wordpress\/?p=62454"},"modified":"2024-06-24T10:24:18","modified_gmt":"2024-06-24T08:24:18","slug":"laura-ingalls-wilder-little-house-in-the-big-woods","status":"publish","type":"post","link":"https:\/\/www.herr-rau.de\/wordpress\/2024\/06\/laura-ingalls-wilder-little-house-in-the-big-woods.htm","title":{"rendered":"Laura Ingalls Wilder, Little House in the Big Woods"},"content":{"rendered":"<div style='text-align:right;'><small>(<a href='https:\/\/www.herr-rau.de\/wordpress\/2024\/06\/laura-ingalls-wilder-little-house-in-the-big-woods.htm#comments'>13 Kommentare.<\/a>)<\/small> <\/div>\n<p class=\"wp-block-paragraph\">Ich hatte bis vor kurzem keines der B\u00fccher um das <em>Little House on the Prairie<\/em> gelesen, hatte wohl auch nie eine ganze Folge von <em>Unsere kleine Farm<\/em> gesehen. Der Serie war ich ein bisschen b\u00f6se, weil in der 3. oder 4. Klasse das gesch\u00e4tzte <em>Bonanza<\/em> nicht mehr im Fernsehen kam, sondern stattdessen diese andere Serie mit Little Joe. Zeitlich sagt Wikipedia, dass das nicht ganz sein kann, <em>Bonanza<\/em> lief angeblich bis 1977, <em>Unsere kleine Farm<\/em> wurde ab 1976 ausgestrahlt. F\u00fcr mich war irgendwie klar, dass das jetzt die weiteren Abenteuer des Little Joe waren, nur eben in Australien. Wieso Australien? Ich wei\u00df es nicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht zuletzt in <em>The Big Bang Theory<\/em> h\u00f6rte man immer wieder davon, und weil mir ein Freund die Reihe empfohlen hat und ich mich ja eh gerade f\u00fcr <a href=\"https:\/\/www.herr-rau.de\/wordpress\/2024\/05\/von-holzfaellern-und-monstern.htm\">Holzf\u00e4llereitum<\/a> interesserte, las ich das erste Buch, das eben nicht in der Pr\u00e4rie oder Kleinstadt spielt, sondern in einer abgelegenen gro\u00dfen Holzh\u00fctte in den damals tiefen W\u00e4ldern von Wisconsin, an der westlichen Grenze zu Minnesota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Buch erz\u00e4hlt vom Ablauf eines typischen Jahres, Winter, Fr\u00fchling, Sommer, Herbst, und den Aufgaben und Herausforderungen und kleinen Freuden, die die jeweilige Zeit mit sich bringt. Die kleine Familie wohnt allein und versorgt sich allein; regelm\u00e4\u00dfig (wie alles regelm\u00e4\u00dfig ist) gibt es Verwandtenbesuche und auch einmal einen Ausflug in die Stadt. Neben dem Jahreszyklus gibt es den w\u00f6chentlichen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Montag: Waschen<\/li>\n\n\n\n<li>Dienstag: B\u00fcgeln<\/li>\n\n\n\n<li>Mittwoch: N\u00e4harbeiten<\/li>\n\n\n\n<li>Donnerstag: Butter machen<\/li>\n\n\n\n<li>Freitag: Putzen<\/li>\n\n\n\n<li>Samstag: Backen<\/li>\n\n\n\n<li>Sonntag: Ruhen<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">All diese Arbeiten werden detailliert, wenn auch verkl\u00e4rt beschrieben. &#8222;Pretty&#8220; schaut die Mutter aus \u00fcber dem Zuber, die \u00c4rmel hochgekrempelt, die Arme wei\u00df und rund, das dunkle Haar leuchtend &#8211; und w\u00e4hrenddessen kriegt sie nie auch nur einen Tropfen Wasser auf das sch\u00f6ne Kleid. (Nicht meine Worte, das steht da so.) W\u00e4hrenddessen jagt der Mann, sieht nach den Fallen, schnitzt Holzspielzeug und Geschenke, gie\u00dft sich die Kugeln f\u00fcr den Vorderlader. Man denkt sich, wie sch\u00f6n so ein einfaches Leben sein k\u00f6nnte! Sich an einfachen Dingen erfreuen, wie der Schweineblase, die die Kinder nach dem Schlachten zum Spielen kriegen, man kann sie aufblasen und hin und her werfen!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend des Lesen hatte ich richtig Lust bekommen, selber ein Reh auszunehmen und zu r\u00e4uchern, ganz so wie im Buch. W\u00e4re nat\u00fcrlich eine ganz schlechte Idee. Eher im Scherz dachte ich mir, dass die ganzen libert\u00e4ren Prepper alle in ihrer Kindheit diese B\u00fccher gelesen und f\u00fcr sie geschw\u00e4rmt haben. Aber ja, da ist wohl etwas dran; die Rechteinhaber nach Ingalls Tod waren politisch aktiv libert\u00e4r.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier kann man sich einen Nachbau des Hauses ansehen: <a href=\"https:\/\/www.lauraingallspepin.com\/lauras-little-house\/\">https:\/\/www.lauraingallspepin.com\/lauras-little-house\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Appetit macht das Buch nicht nur auf ger\u00e4uchertes Wild. Da wird gebacken und gekocht, gep\u00f6kelt und getrocknet, geschlachtet und gek\u00e4st, gestapelt und geflochten und aufgeh\u00e4ngt, je nach fetter oder magerer Jahreszeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enth\u00fclster Mais: Ausgesuchtes Holz wird zu Asche verbrannt, diese in ein S\u00e4ckchen gegeben und zusammen mit den Maisk\u00f6rnern gekocht, bis die Schale abzuplatzen beginnt. Dann wird die Haut sorgf\u00e4ltig in viel Wasser ganz abgerubbelt, und immer wieder gewaschen. Dann hat man nixtamalisierten Mais, in Lauge gekocht und dadurch erst bek\u00f6mmlich gemacht. Gemahlen wird Tortillamehl daraus, in ganzen K\u00f6rnern hei\u00dft das in den S\u00fcdstaaten hominy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Winterbutter: Ist aufgrund des Heu- statt Frischfutters wei\u00dflicher als Sommerbutter. (Recherche ergibt: verh\u00e4lt sich auch etwas anders, ist aber nicht schlechter und nicht weniger fett.) Schon damals f\u00e4rbt die Mutter sie aber gelb, mit in Milch ausgekochten Karottenraspeln, die dann sp\u00e4ter eine Leckerei f\u00fcr die Kinder sind. (Weitere Recherche: Wird heute einheitlich gef\u00e4rbt, um die Kundschaft nicht zu verwirren, und in Deutschland eher gelblich, in Italien eher wei\u00dflich. Ich wei\u00df aber nicht, ob das stimmt.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Getreide wird bereits mechanisch gedroschen, einmal im Jahr kommt eine Maschine vorbei:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Uncle Henry came riding up and tied his horse to a tree. Then he and Pa hitched all the other horses, eight of them, to the smaller machine. They hitched each team to the end of a long stick that came out from the center of the machine. A long iron rod lay along the ground, from this machine to the big machine. [&#8230;]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A man sat on top of the horsepower, and when everything was ready he clucked to the horses, and they began to go. They walked around him in a circle, each team pulling on the long stick to which it was hitched, and following the team ahead. As they went around, they stepped carefully over the tumbling rod, which was tumbling over and over on the ground.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Their pulling made the tumbling rod keep rolling over, and the rod moved the machinery of the separator, which stood beside the stack of wheat.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Das sieht dann so \u00e4hnlich aus wie <a href=\"https:\/\/youtu.be\/051RDV6_y1g\">hier bei Youtube<\/a>:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Horse Powered Threshing Machine\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/051RDV6_y1g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Leichte Lekt\u00fcre, die ein paar Jahrzehnte nach Elizabeth Gaskells <em><s>Candleford<\/s><\/em> Cranford spielt, das ich nur aus der Fernsehfassung mit Judi Dench kenne, und in dem wesentlich realistischer das Leben in einem englischen Dorf geschildert wird. Ich wei\u00df noch nicht, ob ich mit Laura auf die Farm in der Pr\u00e4rie ziehen werde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(13 Kommentare.) Ich hatte bis vor kurzem keines der B\u00fccher um das Little House on the Prairie gelesen, hatte wohl auch nie eine ganze Folge von Unsere kleine Farm gesehen. Der Serie war ich ein bisschen b\u00f6se, weil in der 3. oder 4. Klasse das gesch\u00e4tzte Bonanza nicht mehr im Fernsehen kam, sondern stattdessen diese [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[224],"class_list":["post-62454","post","type-post","status-publish","format-standard","hentry","category-buecher","tag-buecher"],"_links":{"self":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/62454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/comments?post=62454"}],"version-history":[{"count":2,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/62454\/revisions"}],"predecessor-version":[{"id":62526,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/62454\/revisions\/62526"}],"wp:attachment":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/media?parent=62454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/categories?post=62454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/tags?post=62454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}