{"id":64171,"date":"2025-02-08T07:01:44","date_gmt":"2025-02-08T06:01:44","guid":{"rendered":"https:\/\/www.herr-rau.de\/wordpress\/?p=64171"},"modified":"2025-12-29T08:08:52","modified_gmt":"2025-12-29T07:08:52","slug":"vertretungsplanstatistik","status":"publish","type":"post","link":"https:\/\/www.herr-rau.de\/wordpress\/2025\/02\/vertretungsplanstatistik.htm","title":{"rendered":"Statistik zum Vertretungsplan"},"content":{"rendered":"<div style='text-align:right;'><small>(<a href='https:\/\/www.herr-rau.de\/wordpress\/2025\/02\/vertretungsplanstatistik.htm#comments'>1 Kommentare.<\/a>)<\/small> <\/div>\n<p>Manchmal m\u00fcssen Stunden vertreten werden. Manchmal k\u00f6nnen sie stattdessen ausfallen, wenn nicht genug Lehrkr\u00e4fte f\u00fcr eine Vertretung zur Verf\u00fcgung stehen; dieses Ausfallen geschieht \u2013 au\u00dfer in der Oberstufe \u2013 nat\u00fcrlich nur in Randstunden. Deshalb wird in den Randstunden auch insgesamt weniger vertreten als in den anderen Stunden.<\/p>\n\n\n\n<p>Das zeigt das folgende Diagramm. Wenn man die Anzahl der Vertretungen in der 4. Stunde auf 100% festsetzt, werden in der ersten Stunde etwa 55% so viel vertreten, also deutlich weniger.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"407\" src=\"https:\/\/www.herr-rau.de\/wordpress\/archiv\/vertretungsplanstatistik.png\" alt=\"\" class=\"wp-image-64173\" srcset=\"https:\/\/www.herr-rau.de\/wordpress\/archiv\/vertretungsplanstatistik.png 700w, https:\/\/www.herr-rau.de\/wordpress\/archiv\/vertretungsplanstatistik-300x174.png 300w, https:\/\/www.herr-rau.de\/wordpress\/archiv\/vertretungsplanstatistik-150x87.png 150w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p>Dazu habe ich eine Frage, auf die ich keine Antwort wei\u00df:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Warum ist der Wert in der 4. Stunde so viel niedriger als in der 3. und 5. Stunde? (Nat\u00fcrlich ist das relevant: In 3 und 5 sollten demnach mehr Pr\u00e4senzlehrkr\u00e4fte f\u00fcr eventuelle Vertretungen zur Verf\u00fcgung stehen als in 4 oder 2.)<\/li>\n\n\n\n<li>Ist das an anderen Schulen auch so? Diese Verteilung ist in den \u00fcberpr\u00fcften Einzelmonaten \u00e4hnlich wie im gesamten Halbjahr oder im Schuljahr zuvor.<\/li>\n\n\n\n<li>Ist das ein Artefakt (eine Nebenerscheinung, eine zuf\u00e4llige Auswirkung) des Doppelstundenprinzips? Oder hat das etwas mit meinen unbewussten Gewohnheiten bei den Entscheidungen zu tun?<\/li>\n\n\n\n<li>Oder liegt es etwa am diesj\u00e4hrigen Stundenplan, dass in 3 und 5 zuf\u00e4llig Stunden sind, die sich nicht an den Rand verschieben lassen, anders als bei 4?<\/li>\n\n\n\n<li>Sind Exkursionen und dienstliche Abwesenheiten eher in den Stunden 1 bis 3 und 5 bis 6 als in der 4. Stunde?<\/li>\n\n\n\n<li>Feiern Lehrkr\u00e4fte in Pausen so viel, dass sie danach nicht mehr arbeiten k\u00f6nnen?<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(1 Kommentare.) Manchmal m\u00fcssen Stunden vertreten werden. Manchmal k\u00f6nnen sie stattdessen ausfallen, wenn nicht genug Lehrkr\u00e4fte f\u00fcr eine Vertretung zur Verf\u00fcgung stehen; dieses Ausfallen geschieht \u2013 au\u00dfer in der Oberstufe \u2013 nat\u00fcrlich nur in Randstunden. Deshalb wird in den Randstunden auch insgesamt weniger vertreten als in den anderen Stunden. Das zeigt das folgende Diagramm. Wenn [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":64173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[335],"class_list":["post-64171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fundstuecke","tag-vertretungsplan"],"jetpack_featured_media_url":"https:\/\/www.herr-rau.de\/wordpress\/archiv\/vertretungsplanstatistik.png","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/64171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/comments?post=64171"}],"version-history":[{"count":3,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/64171\/revisions"}],"predecessor-version":[{"id":64272,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/posts\/64171\/revisions\/64272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/media\/64173"}],"wp:attachment":[{"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/media?parent=64171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/categories?post=64171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herr-rau.de\/wordpress\/wp-json\/wp\/v2\/tags?post=64171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}